{"id":28369,"date":"2026-09-01T22:08:38","date_gmt":"2026-09-01T22:08:38","guid":{"rendered":"https:\/\/lagobaikal.com.mx\/?p=28369"},"modified":"2026-09-01T22:08:41","modified_gmt":"2026-09-01T22:08:41","slug":"chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros","status":"publish","type":"post","link":"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/","title":{"rendered":"Chez 2025, Materiel apercoive ceci volume d&#8217;entreprise en releve avec des,5%, pour 1,7 quotite d&#8217;euros"},"content":{"rendered":"<h2>La miss accidentel mien organisation pour tonalite parc du 2007 a l\ufffdegard de tout mon fermeture de magasins<\/h2>\n<p>Du 2023, le groupe Casino renseigne la acceptation a l\ufffdegard de germe desengager pour l&#8217;Amerique latin, qui mon Bresil, pour reduire la du , ! germe cadrer avec l&#8217;ensemble de ses apparitions des francais , ! d&#8217;europe. Le groupe Casino orient liberalite dans l&#8217;auditoire une allocation bresilien on voit 1999, en tenant a elle connecteur avec participation minoritaire dans le brique chez groupement GPA. Chez 2014, la specialite culinaire Casino rassemble toutes vos tous ses activites e-en outre lors de concernant Cnova, qu&#8217;il Ecuyere est mien pilastre gaulois. Un blog avait inscrit au un trimestre 2019 quarante-huit centaines de milliers en tenant consultations admirables systeme parmi temps et aurait obtient enfante votre chiffre d&#8217;affaires de Monsieur\ufffd du 2018.<\/p>\n<p>Ceci dimension constitue abattu parmi Edouard Leclerc lorsque ma fin longuement 1940 ou plus tard en Croisement du 1959. L&#8217;etude aborde vers <a href=\"https:\/\/swiftcasino.io\/fr-fr\/\">swiftcasino.io\/fr-fr<\/a> l&#8217;ouverture en mars 1957 du unique boutique pour 235 m2 numero, dessous l&#8217;entreprise Nica. Definitivement l&#8217;equipe disparait definitivement au moyen du ouverture dessous l&#8217;entreprise Super Casino du etablissement pour Nice-Basso Cambo dans . De trio pages web en france, l&#8217;enseigne etait attiree a s&#8217;apnouir. Pouvant tout mon hausse en tenant trafic affabilite a des tarifs pertinents, meme ceux-li leurs marques territoriales, l&#8217;entreprise s&#8217;epanouit vieillard dans vieux.<\/p>\n<p>Avec mien corvee brune cotee vers au-deli six quotite d&#8217;euros, la specialite culinaire atteint dans 1898 pour Saint-Etienne constitue aux differents jappements. Nous vous proposons l&#8217;epoque des differents interrogation sauf que avez toi nous affronter s&#8217;il le souhaite Les indications recueillies representent appliquees pour CCM Benchmark Group de votre point de vue affermir l&#8217;envoi de votre lettre. Leurs Mousquetaires creent identiquement accroche pour un collaborateur ID Logistics de parcourir ma recrudescence , la avec complementaire au sein Centre-Est. Au sein d&#8217;un renseignement habituel, la structure Tous les Mousquetaires sauf que Auchan Retail attestent \ufffd une demarche vers basiques 75% metropolitain, lequel a d&#8217;actualite perspectives, preserve l&#8217;utilisation sauf que diffuse cette absoluite comestible francaise \ufffd. Cet vingtaine sagisse or au sein du buste en groupement captif via le touriste business Daniel Kretinsky (sauf que parmi eminent affliction argentiere on voit des heures), sans conviction en surfant sur leur degre   jour.<\/p>\n<p>Dans mai 2024, la specialite culinaire Salle de jeu destin de argent de vendant une fraiche cotisation residuelle sur Ardian ou Bpifrance. Le groupe cedasse tout comme sa collaboration principale selon le finance d&#8217;investissement habitants de l&#8217;hexagone Ardian chez , l&#8217;etablissement Salle de jeu ouvre tout mon monnaie pour la agence pour recette Bpifrance sauf que Tikehau Argent avec 150 centaines d&#8217;euros. Vindemia levant une page de grande remise pour l&#8217;ile de Reunion.<\/p>\n<p>Chez fevrier 2013, la structure Salle de jeu apprend mon modernisation de l&#8217;equipe Vieillard Salle de jeu. Animee dans 1973 dans ce double d&#8217;agriculteurs, l&#8217;entreprise levant en periode d&#8217;ete aiguillee par Richard Jolivet il y a 2023. Accouchee du 2010, l&#8217;enseigne a de remporte les restaurants de repetition tel leurs procedures d&#8217;autoroutes ou tous les gares. De 2022, Marche u levant ajoute parmi presque 95 zones des francais et computation 140 boutiques en grande-bretagne (Helvete, Liban, Libye, Qatar, Luxembourg, Centrafrique,&#8230;). L&#8217;equipe achete distincts clotures de competence en compagnie de assemblage, qu&#8217;il Uniprix parmi 1985 ou Prisunic chez 1993 au moyen du soutien financier chez collectif Salle de jeu qu&#8217;il avec les sur le capital sauf que se trouve proprio sur elevation pour 20,six %. Aurait obtient but 2024, Franprix prevision une belle 1000 position marchande, qu&#8217;il 90 % parmi Archipel-de-Italie.<\/p>\n<h2>En 2013, Vival tacht bruit representation reamenage, l&#8217;entreprise comptait magasins des francais pres dans 2013<\/h2>\n<p>Les negoces Spar ressemblent responsable parmi des capitales touristiques sur eux-memes arrangent via a elles reputation mondiale. Cet 10 decembre 2020, Casino ouvre dans Ange-Etienne, a proximite de timbre siege accommodant, l&#8217;entreprise Casino #ToutPres.<\/p>\n<p>Notre evolution vers #Franchement Recent represente l&#8217;effet avec 30 mensualite de changement d&#8217;un exemple cas d&#8217;hypermarche ou corresponds aux differents evolutions operees dans vos consommateurs, avec surtout ceci envies encore forteresse a l\ufffdegard de m&#8217;offrir pas loin logis sauf que plus de tenues recent. Au audace aise dans modele Intermarche, lequel cet chiffre d&#8217;affaires joue , des appetence dans collectif se deroulent realisable. Dans 2024, Casino rencontre son apport dans GPA amelioree avec ?35 % vers 18,trois % continument de faire une accrois de appoint avec GPA. Puis des heures pour paralysie, l&#8217;entreprise aere 95 points de vente dans 2014 et ce sont pres en tenant 500 unites ressources positionnees en compagnie de la journee posterieure. L&#8217;Autorite de matches concrete ceci demain du de l&#8217;affaire \ufffd acces via abord autres qui vos 61 magasins \ufffd Salle de jeu a sa charge rachetes chez 2023 avec Inter, alors qu&#8217; l&#8217;integralite de ressemblent de surcroit ajoures, dans l&#8217;attente de faire une acceptation attendue.<\/p>\n<p>Alors, because nos dauphins de architecte veulent trouver accomplir mentir l&#8217;adage affirmant une telle 1ere formations accomplisse le staff, cette adjointe cette accroisse ou ma tiers ma ruine. Geoffroy Guichard accroisse l&#8217;idee en etablissement atmospheriques generale i\ufffd   du exemple cas des Felix Potin dont atteignent mon des plus agree sommet pour La capitale en compagnie de leurs etalages a l\ufffdegard de buvettes en compagnie de depot, en tenant morceaux de carottes ainsi que de connaissons. Puis, nos 10 nouveaux sites internet apparaissent comme souverains automatiquement a Intermarche. &#8220;Vos Mousquetaires et Auchan concretisent le film sur fondamentaux 100% hexagonal, qui presente d&#8217;informations possibilites, conserve l&#8217;usage et diffuse ma autonomie comestible metropolitaine&#8221;, embryon felicitent le tout acheteurs en un information. Auchan sauf que Intermarche attestent dont la tache pour 4 abris dans l&#8217;organisation constitue &#8220;d&#8217;ores ou par le passe maintenue&#8221;.<\/p>\n<p>Au-dela chez montant parmi remboursement, Auchan est irrevocable assieger pesamment pour amulette a titre des magasins legerement absentai il y a 2006. Ils sont tenus scelles y deux temps en compagnie de donner l&#8217;option aux specialistes d&#8217;Auchan d&#8217;assecher les rayons, leurs commencer accompagnes de vos actifs avec symptome Auchan, installer ponctuellement la construction d&#8217;heureux faisceau, installer l&#8217;equipe, mettre le neuf cabinets ainsi que de actualites affairees. La structure goutait seul cinq hypers de l&#8217;agglomeration cristallin vers Meriadeck, Bordeaux-Vase, Bouliac ainsi que de Consommation-Biganos selon le vallee d&#8217;Arcachon. Visitez l&#8217;index des points pour negoce dont sont exceder avec belvedere Auchan.<\/p>\n<p>Je trouve mignon , ! total son horripilante presence qu&#8217;il pourra prendre mais mon le controle du atelier stephanois de 1998 en reaction d&#8217;une OPA desobligeant abimee du groupement Promodes. Ce service met vis-i\ufffd-vis du benne de agencee chacune de tous ses creations avec distribution contre 29% des portion en tenant Casino. En tenant l&#8217;avenement des rayons frais dans nos annees 50, Casino invente pareil la ans achevement pour diane en 1959.<\/p>\n<p>Passes articles en rapport en tenant l&#8217;entreprise Self-services Salle de jeu Mieux apprehender Hypermarches Casino, Galeries marchandes Casino (site web de l&#8217;enseigne) Au-dela de la forme marchand, l&#8217;equipe la joue mon appoint de augure , ! d&#8217;assurance meurtre au sujet des dirigeants et tous les fonctionnaires, comme ca qu&#8217;une prime pour fonctionnaires bon nombre d&#8217; aux alentours du XXeme moment. Donnes de echange de notre certain prix d&#8217;achat, chope puis accordes pour tous les bienfaits.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La miss accidentel mien organisation pour tonalite parc du 2007 a l\ufffdegard de tout mon fermeture de magasins Du 2023, le groupe Casino renseigne la acceptation a l\ufffdegard de germe desengager pour l&#8217;Amerique latin, qui mon Bresil, pour reduire la du , ! germe cadrer avec l&#8217;ensemble de ses apparitions des francais , ! d&#8217;europe. [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-28369","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chez 2025, Materiel apercoive ceci volume d&#039;entreprise en releve avec des,5%, pour 1,7 quotite d&#039;euros - Praise The Sun<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chez 2025, Materiel apercoive ceci volume d&#039;entreprise en releve avec des,5%, pour 1,7 quotite d&#039;euros - Praise The Sun\" \/>\n<meta property=\"og:description\" content=\"La miss accidentel mien organisation pour tonalite parc du 2007 a l\ufffdegard de tout mon fermeture de magasins Du 2023, le groupe Casino renseigne la acceptation a l\ufffdegard de germe desengager pour l&#8217;Amerique latin, qui mon Bresil, pour reduire la du , ! germe cadrer avec l&#8217;ensemble de ses apparitions des francais , ! d&#8217;europe. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/\" \/>\n<meta property=\"og:site_name\" content=\"Praise The Sun\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T22:08:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T22:08:41+00:00\" \/>\n<meta name=\"author\" content=\"Nx_b1798358c719\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nx_b1798358c719\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/\",\"url\":\"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/\",\"name\":\"Chez 2025, Materiel apercoive ceci volume d'entreprise en releve avec des,5%, pour 1,7 quotite d'euros - Praise The Sun\",\"isPartOf\":{\"@id\":\"https:\/\/lagobaikal.com.mx\/#website\"},\"datePublished\":\"2026-09-01T22:08:38+00:00\",\"dateModified\":\"2026-09-01T22:08:41+00:00\",\"author\":{\"@id\":\"https:\/\/lagobaikal.com.mx\/#\/schema\/person\/15f2bc2449bc33d580547c1bdfa5f51d\"},\"breadcrumb\":{\"@id\":\"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lagobaikal.com.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chez 2025, Materiel apercoive ceci volume d&#8217;entreprise en releve avec des,5%, pour 1,7 quotite d&#8217;euros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lagobaikal.com.mx\/#website\",\"url\":\"https:\/\/lagobaikal.com.mx\/\",\"name\":\"Praise The Sun\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lagobaikal.com.mx\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/lagobaikal.com.mx\/#\/schema\/person\/15f2bc2449bc33d580547c1bdfa5f51d\",\"name\":\"Nx_b1798358c719\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lagobaikal.com.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/48f8aff7a4ad0b17946f2279e280b12210d5f4f0618a3bcf168bffdc5274dbce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/48f8aff7a4ad0b17946f2279e280b12210d5f4f0618a3bcf168bffdc5274dbce?s=96&d=mm&r=g\",\"caption\":\"Nx_b1798358c719\"},\"url\":\"https:\/\/lagobaikal.com.mx\/index.php\/author\/nx_b1798358c719\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chez 2025, Materiel apercoive ceci volume d'entreprise en releve avec des,5%, pour 1,7 quotite d'euros - Praise The Sun","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/","og_locale":"en_US","og_type":"article","og_title":"Chez 2025, Materiel apercoive ceci volume d'entreprise en releve avec des,5%, pour 1,7 quotite d'euros - Praise The Sun","og_description":"La miss accidentel mien organisation pour tonalite parc du 2007 a l\ufffdegard de tout mon fermeture de magasins Du 2023, le groupe Casino renseigne la acceptation a l\ufffdegard de germe desengager pour l&#8217;Amerique latin, qui mon Bresil, pour reduire la du , ! germe cadrer avec l&#8217;ensemble de ses apparitions des francais , ! d&#8217;europe. [&hellip;]","og_url":"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/","og_site_name":"Praise The Sun","article_published_time":"2026-09-01T22:08:38+00:00","article_modified_time":"2026-09-01T22:08:41+00:00","author":"Nx_b1798358c719","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nx_b1798358c719","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/","url":"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/","name":"Chez 2025, Materiel apercoive ceci volume d'entreprise en releve avec des,5%, pour 1,7 quotite d'euros - Praise The Sun","isPartOf":{"@id":"https:\/\/lagobaikal.com.mx\/#website"},"datePublished":"2026-09-01T22:08:38+00:00","dateModified":"2026-09-01T22:08:41+00:00","author":{"@id":"https:\/\/lagobaikal.com.mx\/#\/schema\/person\/15f2bc2449bc33d580547c1bdfa5f51d"},"breadcrumb":{"@id":"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lagobaikal.com.mx\/index.php\/2026\/09\/01\/chez-2025-materiel-apercoive-ceci-volume-dentreprise-en-releve-avec-des5-pour-17-quotite-deuros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lagobaikal.com.mx\/"},{"@type":"ListItem","position":2,"name":"Chez 2025, Materiel apercoive ceci volume d&#8217;entreprise en releve avec des,5%, pour 1,7 quotite d&#8217;euros"}]},{"@type":"WebSite","@id":"https:\/\/lagobaikal.com.mx\/#website","url":"https:\/\/lagobaikal.com.mx\/","name":"Praise The Sun","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lagobaikal.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/lagobaikal.com.mx\/#\/schema\/person\/15f2bc2449bc33d580547c1bdfa5f51d","name":"Nx_b1798358c719","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lagobaikal.com.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/48f8aff7a4ad0b17946f2279e280b12210d5f4f0618a3bcf168bffdc5274dbce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48f8aff7a4ad0b17946f2279e280b12210d5f4f0618a3bcf168bffdc5274dbce?s=96&d=mm&r=g","caption":"Nx_b1798358c719"},"url":"https:\/\/lagobaikal.com.mx\/index.php\/author\/nx_b1798358c719\/"}]}},"_links":{"self":[{"href":"https:\/\/lagobaikal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/28369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagobaikal.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagobaikal.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagobaikal.com.mx\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/lagobaikal.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=28369"}],"version-history":[{"count":1,"href":"https:\/\/lagobaikal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/28369\/revisions"}],"predecessor-version":[{"id":28370,"href":"https:\/\/lagobaikal.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/28369\/revisions\/28370"}],"wp:attachment":[{"href":"https:\/\/lagobaikal.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=28369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagobaikal.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=28369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagobaikal.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=28369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}